{"id":57146,"date":"2021-10-28T14:37:07","date_gmt":"2021-10-28T19:37:07","guid":{"rendered":"https:\/\/test.logity.co\/site\/?p=57146"},"modified":"2021-10-28T14:37:07","modified_gmt":"2021-10-28T19:37:07","slug":"logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial","status":"publish","type":"post","link":"https:\/\/logity.com\/site\/pt\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\/","title":{"rendered":"Logity Lobby um elemento chave para a comunica\u00e7\u00e3o do seu complexo residencial."},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"57146\" class=\"elementor elementor-57146\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3dfefc86 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3dfefc86\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2bce5b43\" data-id=\"2bce5b43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20ed21eb elementor-widget elementor-widget-text-editor\" data-id=\"20ed21eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Um meio de comunica\u00e7\u00e3o eficaz que une comunidades residenciais, usando v\u00eddeo porteiro inteligente. O Logity Lobby elimina fia\u00e7\u00e3o, dutos e equipamentos desnecess\u00e1rios dentro das resid\u00eancias, pois funciona em um aplicativo pr\u00f3prio que chega diretamente ao celular do morador, sem que ele precise fornecer seus dados pessoais, pois utiliza c\u00f3digos QR exclusivos para cada resid\u00eancia.<\/strong><\/p><p>Atualmente mais de 60% da popula\u00e7\u00e3o do pa\u00eds vive em propriedade horizontal, seja de um pequeno pr\u00e9dio que o acomoda com v\u00e1rios apartamentos dentro ou de grandes complexos com capacidade de at\u00e9 500 unidades residenciais. Figuras que ele joga em n\u00f3s <a href=\"https:\/\/www.eltiempo.com\/economia\/sectores\/mas-conjuntos-residenciales-en-colombia-donde-la-convivencia-es-una-necesidad-257136\" target=\"_blank\" rel=\"noopener\">o jornal informativo EL TIEMPO<\/a>. Um n\u00famero que aumenta dia a dia e resulta em pequenas comunidades residenciais espalhadas por todas as cidades do pa\u00eds, com um grande desafio em termos de comunica\u00e7\u00e3o, conviv\u00eancia e seguran\u00e7a dos propriet\u00e1rios e moradores deste regime habitacional.<\/p><p>Portanto, os problemas mais recorrentes que foram detectados ao longo dos anos na copropriedade s\u00e3o:<\/p><ul><li>Danos cont\u00ednuos ao sistema de comunica\u00e7\u00e3o existente, devido a m\u00e1s pr\u00e1ticas de constru\u00e7\u00e3o e engenharia. Geralmente, a mesma conduta \u00e9 utilizada para estender as diferentes redes dos v\u00e1rios operadores, coexistindo com o intercomunicador com fios.<\/li><li>N\u00e3o h\u00e1 comunica\u00e7\u00e3o efetiva entre a administra\u00e7\u00e3o e os moradores ou propriet\u00e1rios<\/li><li>Entre outras coisas, por sua relut\u00e2ncia em entregar seus dados pessoais, o que acompanha a obriga\u00e7\u00e3o por parte da administra\u00e7\u00e3o de processar os dados e implementar as pol\u00edticas de Habeas Data de acordo com a Lei 1.581 de 2012 e a supervis\u00e3o da Superintend\u00eancia da Ind\u00fastria e Com\u00e9rcio.<\/li><li>Os problemas de seguran\u00e7a que existem em cada edif\u00edcio dada a informalidade com que se trata o registo de visitantes e fam\u00edlias.<\/li><\/ul><p>A Logity nasceu da necessidade de encontrar uma solu\u00e7\u00e3o para estes problemas atrav\u00e9s do seu produto Logity Lobby. Um meio de comunica\u00e7\u00e3o eficaz que une comunidades residenciais, utilizando como meio o videoporteiro inteligente. Eliminando fia\u00e7\u00e3o, dutos e equipamentos desnecess\u00e1rios dentro das resid\u00eancias, pois funciona em um aplicativo pr\u00f3prio que os moradores baixam em seus celulares, seja Android ou iPhone, sem precisar fornecer seus dados pessoais, pois \u00e9 tratado por c\u00f3digos QR exclusivos para cada resid\u00eancia.<\/p><p>\u00a0<\/p><p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-57148 size-full\" src=\"http:\/\/test.logity.co\/site\/wp-content\/uploads\/2021\/10\/Imagenes-complementarias-articulos-4.jpg\" alt=\"\" width=\"900\" height=\"450\" srcset=\"https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Imagenes-complementarias-articulos-4.jpg 900w, https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Imagenes-complementarias-articulos-4-300x150.jpg 300w, https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Imagenes-complementarias-articulos-4-768x384.jpg 768w, https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Imagenes-complementarias-articulos-4-18x9.jpg 18w, https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Imagenes-complementarias-articulos-4-480x240.jpg 480w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>Sem preju\u00edzo do anterior, tamb\u00e9m opera em telefones fixos e celulares de baixa tecnologia, oferecendo cobertura 100% da popula\u00e7\u00e3o residente.<\/p><p>Para a administra\u00e7\u00e3o, \u00e9 entregue uma ferramenta de gest\u00e3o na nuvem da internet chamada: <strong>Administrador da Web<\/strong> com 10 m\u00f3dulos interativos, que facilitam a tarefa e economizam tempo e recursos para o gerente da obra.<\/p><p>Os equipamentos s\u00e3o instalados nos port\u00f5es, uma solu\u00e7\u00e3o chave na m\u00e3o de acordo com as necessidades do edif\u00edcio, ou seja, a consola Logity que se integra com outros equipamentos adicionais como Leitor de Cart\u00f5es, Impressora de Bilhetes, Intercomunicadores, entre outros.<\/p><p>O Logity Console foi projetado tendo em mente a facilidade de uso para o pessoal de vigil\u00e2ncia. Um dispositivo all-in-one, com baixo consumo de energia e que n\u00e3o ocupa mais espa\u00e7o, n\u00e3o se enche de v\u00edrus como acontece com um computador. \u00c9 composto por um poderoso processador que controla uma tela sens\u00edvel ao toque, um telefone de \u00faltima gera\u00e7\u00e3o e uma c\u00e2mera de v\u00eddeo, com porta USB e Bluetooth para conex\u00e3o com equipamentos perif\u00e9ricos.<\/p><p>Cada casa pode baixar at\u00e9 5 aplicativos mais dois n\u00fameros adicionais, fixos ou m\u00f3veis. Em outras palavras, a Logity garante a comunica\u00e7\u00e3o para toda a comunidade residencial. A partir do aplicativo, voc\u00ea pode chamar o objetivo diretamente. Tamb\u00e9m inclu\u00edmos um n\u00famero DID (telefone fixo da cidade) exclusivo para cada Pool, que pode ser chamado diretamente e se conecta diretamente ao Logity Console.<\/p><h4>\u00a0<\/h4><h4>Por favor, compartilhe esta informa\u00e7\u00e3o de interesse com seus colegas e amigos.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-da00c09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da00c09\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f37348a\" data-id=\"f37348a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a0abbc elementor-widget elementor-widget-heading\" data-id=\"1a0abbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><h1 style=\"white-space: normal\"><\/h1><h4><span style=\"font-size: 27px;font-weight: 700\">t\u00f3picos relacionados<\/span><\/h4><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-275ee72 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"275ee72\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;3&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-58685 post type-post status-publish format-standard has-post-thumbnail hentry category-sin-categoria\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/logity.com\/site\/pt\/vale-la-pena-instalar-un-videoportero-inteligente-ventajas-funciones-y-beneficios\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/logity.com\/site\/wp-content\/uploads\/2025\/08\/delivery-guy-clicking-bell_23-2148593098-300x225.jpg\" class=\"attachment-medium size-medium wp-image-58687\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/logity.com\/site\/pt\/vale-la-pena-instalar-un-videoportero-inteligente-ventajas-funciones-y-beneficios\/\" >\n\t\t\t\t\u00bfVale la pena instalar un videoportero inteligente? Ventajas, funciones y beneficios\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t08\/08\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNenhum coment\u00e1rio\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>En el mundo actual, la seguridad y el control de acceso se han convertido en aspectos cruciales para cualquier propiedad. Una de las herramientas m\u00e1s<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/logity.com\/site\/pt\/vale-la-pena-instalar-un-videoportero-inteligente-ventajas-funciones-y-beneficios\/\" aria-label=\"Leia mais sobre \u00bfVale la pena instalar un videoportero inteligente? Ventajas, funciones y beneficios\" tabindex=\"-1\" >\n\t\t\tConsulte Mais informa\u00e7\u00e3o &quot;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-58677 post type-post status-publish format-standard has-post-thumbnail hentry category-sin-categoria\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/logity.com\/site\/pt\/citofono-ip-vs-citofono-analogico-ventajas-diferencias-y-cual-elegir-para-su-propiedad\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/logity.com\/site\/wp-content\/uploads\/2025\/08\/shot-pretty-young-woman-using-home-automation-system-digital-tablet-regulate-temperature_519356-1881-300x200.jpg\" class=\"attachment-medium size-medium wp-image-58680\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/logity.com\/site\/pt\/citofono-ip-vs-citofono-analogico-ventajas-diferencias-y-cual-elegir-para-su-propiedad\/\" >\n\t\t\t\tCit\u00f3fono IP vs. Cit\u00f3fono anal\u00f3gico: ventajas, diferencias y cu\u00e1l elegir para su propiedad\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t08\/08\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNenhum coment\u00e1rio\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>La seguridad y el control de acceso son aspectos fundamentales en cualquier tipo de propiedad, ya sea residencial, comercial o empresarial. Una de las herramientas<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/logity.com\/site\/pt\/citofono-ip-vs-citofono-analogico-ventajas-diferencias-y-cual-elegir-para-su-propiedad\/\" aria-label=\"Leia mais sobre Cit\u00f3fono IP vs. Cit\u00f3fono anal\u00f3gico: ventajas, diferencias y cu\u00e1l elegir para su propiedad\" tabindex=\"-1\" >\n\t\t\tConsulte Mais informa\u00e7\u00e3o &quot;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-58588 post type-post status-publish format-standard has-post-thumbnail hentry category-sin-categoria\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/logity.com\/site\/pt\/la-evolucion-del-acceso-residencial-como-el-acceso-inteligente-y-la-citofonia-inteligente-estan-transformando-los-edificios-modernos\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/logity.com\/site\/wp-content\/uploads\/2025\/07\/woman-touching-control-panel-wall-corridor_259150-60378-300x200.jpg\" class=\"attachment-medium size-medium wp-image-58591\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/logity.com\/site\/pt\/la-evolucion-del-acceso-residencial-como-el-acceso-inteligente-y-la-citofonia-inteligente-estan-transformando-los-edificios-modernos\/\" >\n\t\t\t\tLa evoluci\u00f3n del acceso residencial: c\u00f3mo el acceso inteligente y la citofon\u00eda inteligente est\u00e1n transformando los edificios modernos\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t16\/07\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNenhum coment\u00e1rio\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u00bfQu\u00e9 es el control de acceso para edificios y por qu\u00e9 es tan importante hoy? El control de acceso para edificios se refiere al conjunto<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/logity.com\/site\/pt\/la-evolucion-del-acceso-residencial-como-el-acceso-inteligente-y-la-citofonia-inteligente-estan-transformando-los-edificios-modernos\/\" aria-label=\"Leia mais sobre La evoluci\u00f3n del acceso residencial: c\u00f3mo el acceso inteligente y la citofon\u00eda inteligente est\u00e1n transformando los edificios modernos\" tabindex=\"-1\" >\n\t\t\tConsulte Mais informa\u00e7\u00e3o &quot;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Un medio de comunicaci\u00f3n efectivo que une las comunidades residenciales, utilizando video citofon\u00eda inteligente.\u00a0 Logity Lobby elimina cableados, ductos y equipos innecesarios dentro de las viviendas, porque funciona sobre una aplicaci\u00f3n propia que llega directo al celular del residente, sin que tengan que suministrar sus datos personales porque utilizan c\u00f3digos QR \u00fanicos para cada vivienda. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":57147,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-57146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-video-citofonia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Logity Lobby un elemento clave para la comunicaci\u00f3n de tu conjunto residencial. - Logity<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/logity.com\/site\/pt\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Logity Lobby un elemento clave para la comunicaci\u00f3n de tu conjunto residencial.\" \/>\n<meta property=\"og:description\" content=\"Un medio de comunicaci\u00f3n efectivo que une las comunidades residenciales, utilizando video citofon\u00eda inteligente.\u00a0 Logity Lobby elimina cableados, ductos y equipos innecesarios dentro de las viviendas, porque funciona sobre una aplicaci\u00f3n propia que llega directo al celular del residente, sin que tengan que suministrar sus datos personales porque utilizan c\u00f3digos QR \u00fanicos para cada vivienda. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/logity.com\/site\/pt\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\/\" \/>\n<meta property=\"og:site_name\" content=\"Logity\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-28T19:37:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Articulos-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t<meta property=\"og:image:height\" content=\"372\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Logity\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Logity\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\\\/\"},\"author\":{\"name\":\"Logity\",\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/#\\\/schema\\\/person\\\/de3b49e6d80ca08ca6272eceeb057a4f\"},\"headline\":\"Logity Lobby un elemento clave para la comunicaci\u00f3n de tu conjunto residencial.\",\"datePublished\":\"2021-10-28T19:37:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\\\/\"},\"wordCount\":700,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/logity.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Articulos-5.jpg\",\"articleSection\":[\"Video citofonia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/logity.com\\\/site\\\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\\\/\",\"url\":\"https:\\\/\\\/logity.com\\\/site\\\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\\\/\",\"name\":\"Logity Lobby un elemento clave para la comunicaci\u00f3n de tu conjunto residencial. - Logity\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/logity.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Articulos-5.jpg\",\"datePublished\":\"2021-10-28T19:37:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/#\\\/schema\\\/person\\\/de3b49e6d80ca08ca6272eceeb057a4f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/logity.com\\\/site\\\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/logity.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Articulos-5.jpg\",\"contentUrl\":\"https:\\\/\\\/logity.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Articulos-5.jpg\",\"width\":980,\"height\":372},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/logity.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Logity Lobby un elemento clave para la comunicaci\u00f3n de tu conjunto residencial.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/logity.com\\\/site\\\/\",\"name\":\"Logity\",\"description\":\"Citofon\u00eda Virtual Inteligente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/logity.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/#\\\/schema\\\/person\\\/de3b49e6d80ca08ca6272eceeb057a4f\",\"name\":\"Logity\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa9704a026975daece93256998a9d8bf460822a7b813251839bcf3edb214ca45?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa9704a026975daece93256998a9d8bf460822a7b813251839bcf3edb214ca45?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa9704a026975daece93256998a9d8bf460822a7b813251839bcf3edb214ca45?s=96&d=mm&r=g\",\"caption\":\"Logity\"},\"url\":\"https:\\\/\\\/logity.com\\\/site\\\/pt\\\/author\\\/logity\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Logity Lobby un elemento clave para la comunicaci\u00f3n de tu conjunto residencial. - Logity","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/logity.com\/site\/pt\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\/","og_locale":"pt_BR","og_type":"article","og_title":"Logity Lobby un elemento clave para la comunicaci\u00f3n de tu conjunto residencial.","og_description":"Un medio de comunicaci\u00f3n efectivo que une las comunidades residenciales, utilizando video citofon\u00eda inteligente.\u00a0 Logity Lobby elimina cableados, ductos y equipos innecesarios dentro de las viviendas, porque funciona sobre una aplicaci\u00f3n propia que llega directo al celular del residente, sin que tengan que suministrar sus datos personales porque utilizan c\u00f3digos QR \u00fanicos para cada vivienda. [&hellip;]","og_url":"https:\/\/logity.com\/site\/pt\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\/","og_site_name":"Logity","article_published_time":"2021-10-28T19:37:07+00:00","og_image":[{"width":980,"height":372,"url":"https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Articulos-5.jpg","type":"image\/jpeg"}],"author":"Logity","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Logity","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/logity.com\/site\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\/#article","isPartOf":{"@id":"https:\/\/logity.com\/site\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\/"},"author":{"name":"Logity","@id":"https:\/\/logity.com\/site\/#\/schema\/person\/de3b49e6d80ca08ca6272eceeb057a4f"},"headline":"Logity Lobby un elemento clave para la comunicaci\u00f3n de tu conjunto residencial.","datePublished":"2021-10-28T19:37:07+00:00","mainEntityOfPage":{"@id":"https:\/\/logity.com\/site\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\/"},"wordCount":700,"commentCount":0,"image":{"@id":"https:\/\/logity.com\/site\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\/#primaryimage"},"thumbnailUrl":"https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Articulos-5.jpg","articleSection":["Video citofonia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/logity.com\/site\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/logity.com\/site\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\/","url":"https:\/\/logity.com\/site\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\/","name":"Logity Lobby un elemento clave para la comunicaci\u00f3n de tu conjunto residencial. - Logity","isPartOf":{"@id":"https:\/\/logity.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/logity.com\/site\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\/#primaryimage"},"image":{"@id":"https:\/\/logity.com\/site\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\/#primaryimage"},"thumbnailUrl":"https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Articulos-5.jpg","datePublished":"2021-10-28T19:37:07+00:00","author":{"@id":"https:\/\/logity.com\/site\/#\/schema\/person\/de3b49e6d80ca08ca6272eceeb057a4f"},"breadcrumb":{"@id":"https:\/\/logity.com\/site\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/logity.com\/site\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/logity.com\/site\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\/#primaryimage","url":"https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Articulos-5.jpg","contentUrl":"https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Articulos-5.jpg","width":980,"height":372},{"@type":"BreadcrumbList","@id":"https:\/\/logity.com\/site\/logity-lobby-un-elemento-clave-para-la-comunicacion-de-tu-conjunto-residencial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/logity.com\/site\/"},{"@type":"ListItem","position":2,"name":"Logity Lobby un elemento clave para la comunicaci\u00f3n de tu conjunto residencial."}]},{"@type":"WebSite","@id":"https:\/\/logity.com\/site\/#website","url":"https:\/\/logity.com\/site\/","name":"Logidade","description":"Sistema de telefone virtual inteligente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/logity.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/logity.com\/site\/#\/schema\/person\/de3b49e6d80ca08ca6272eceeb057a4f","name":"Logidade","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/fa9704a026975daece93256998a9d8bf460822a7b813251839bcf3edb214ca45?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fa9704a026975daece93256998a9d8bf460822a7b813251839bcf3edb214ca45?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa9704a026975daece93256998a9d8bf460822a7b813251839bcf3edb214ca45?s=96&d=mm&r=g","caption":"Logity"},"url":"https:\/\/logity.com\/site\/pt\/author\/logity\/"}]}},"jetpack_featured_media_url":"https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Articulos-5.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/logity.com\/site\/pt\/wp-json\/wp\/v2\/posts\/57146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/logity.com\/site\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/logity.com\/site\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/logity.com\/site\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/logity.com\/site\/pt\/wp-json\/wp\/v2\/comments?post=57146"}],"version-history":[{"count":0,"href":"https:\/\/logity.com\/site\/pt\/wp-json\/wp\/v2\/posts\/57146\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/logity.com\/site\/pt\/wp-json\/wp\/v2\/media\/57147"}],"wp:attachment":[{"href":"https:\/\/logity.com\/site\/pt\/wp-json\/wp\/v2\/media?parent=57146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/logity.com\/site\/pt\/wp-json\/wp\/v2\/categories?post=57146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/logity.com\/site\/pt\/wp-json\/wp\/v2\/tags?post=57146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}