{"id":57124,"date":"2021-10-12T09:45:07","date_gmt":"2021-10-12T14:45:07","guid":{"rendered":"https:\/\/test.logity.co\/site\/?p=57124"},"modified":"2021-10-12T09:45:07","modified_gmt":"2021-10-12T14:45:07","slug":"y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad","status":"publish","type":"post","link":"https:\/\/logity.com\/site\/pt\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\/","title":{"rendered":"E se o WhatsApp cair completamente amanh\u00e3? O que aconteceria com a comunica\u00e7\u00e3o em sua comunidade?"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"57124\" class=\"elementor elementor-57124\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3dfefc86 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3dfefc86\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2bce5b43\" data-id=\"2bce5b43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20ed21eb elementor-widget elementor-widget-text-editor\" data-id=\"20ed21eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Na segunda-feira, 4 de outubro, o aplicativo gratuito de mensagens instant\u00e2neas registrou queda mundial. Uma falha que nos deixa com muita reflex\u00e3o ao avaliar se a comunica\u00e7\u00e3o da sua gest\u00e3o administrativa e da comunidade residencial depende desta aplica\u00e7\u00e3o.<\/strong><\/p><p>A primeira falha que o WhatsApp apresentou foi em sua vers\u00e3o Web e posteriormente em telefones e outros dispositivos m\u00f3veis. Um dia que ficou marcado na hist\u00f3ria pelos coment\u00e1rios feitos por usu\u00e1rios que expressaram suas grandes perdas monet\u00e1rias e em seu trabalho pelas quase 5 horas que durou o servi\u00e7o de mensagens inativo. Adversidades que nos fazem pensar e repensar, o que acontece se eu deixar toda a minha comunica\u00e7\u00e3o contando com apenas uma ferramenta.<\/p><p>Portanto, al\u00e9m de pensar e ficar apenas alarmado, a solu\u00e7\u00e3o para esse tipo de falha \u00e9 encontrar uma alternativa exata e n\u00e3o apenas confiar em um meio de comunica\u00e7\u00e3o. \u00c9 preciso garantir que a informa\u00e7\u00e3o continue seu fluxo de forma adequada, por meio de uma ferramenta que formalize a mensagem de forma tempestiva e organizada.<\/p><p>\u00a0<\/p><p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-57126 size-full\" src=\"http:\/\/test.logity.co\/site\/wp-content\/uploads\/2021\/10\/Imagenes-complementarias-articulos-2.jpg\" alt=\"\" width=\"900\" height=\"450\" srcset=\"https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Imagenes-complementarias-articulos-2.jpg 900w, https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Imagenes-complementarias-articulos-2-300x150.jpg 300w, https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Imagenes-complementarias-articulos-2-768x384.jpg 768w, https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Imagenes-complementarias-articulos-2-18x9.jpg 18w, https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Imagenes-complementarias-articulos-2-480x240.jpg 480w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p><p>\u00a0<\/p><p>A tecnologia desempenha um papel muito importante na busca de solu\u00e7\u00f5es exatas, por isso nasceu a Logity, o meio de comunica\u00e7\u00e3o inteligente destinado a conectar as comunidades da Propriedade Horizontal com servi\u00e7os, produtos e fornecedores, sem fornecer dados pessoais. Ao adquirir os nossos produtos garante uma plataforma \u00fanica para a sua copropriedade, com um servi\u00e7o de comunica\u00e7\u00e3o permanente a partir de qualquer parte do mundo onde se encontre. Al\u00e9m disso, mensagens entre o administrador e os moradores que chegam diretamente na tela do seu celular atrav\u00e9s do nosso pr\u00f3prio aplicativo.<\/p><p>No entanto, ao ter o nosso v\u00eddeo porteiro, est\u00e1 a garantir tamb\u00e9m o Web Admin. OU<strong>n portal web projetado para administradores. Cont\u00e9m <\/strong>10 m\u00f3dulos com excelentes solu\u00e7\u00f5es de organiza\u00e7\u00e3o, mensagens privadas e base de dados com motor de busca inteligente, entre outros. Fun\u00e7\u00f5es essenciais para garantir a comunica\u00e7\u00e3o em sua propriedade a qualquer momento.<\/p><p>Em conclus\u00e3o, a moral do que aconteceu h\u00e1 alguns dias \u00e9: n\u00e3o devemos confiar em uma \u00fanica ferramenta para comunicar ou coletar dados importantes, \u00e9 sempre necess\u00e1rio ter uma alternativa que nos ajude para essas situa\u00e7\u00f5es fortuitas que saem do controle e \u00e9 assim que estaremos preparados para qualquer eventualidade. Lembre-se, a Logity \u00e9 o melhor aliado que voc\u00ea pode encontrar para sua copropriedade.<\/p><h4>\u00a0<\/h4><h4>Por favor, compartilhe esta informa\u00e7\u00e3o de interesse com seus colegas e amigos.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-da00c09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da00c09\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f37348a\" data-id=\"f37348a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a0abbc elementor-widget elementor-widget-heading\" data-id=\"1a0abbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><h1 style=\"white-space: normal\"><\/h1><h4><span style=\"font-size: 27px;font-weight: 700\">t\u00f3picos relacionados<\/span><\/h4><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-275ee72 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"275ee72\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;3&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-58685 post type-post status-publish format-standard has-post-thumbnail hentry category-sin-categoria\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/logity.com\/site\/pt\/vale-la-pena-instalar-un-videoportero-inteligente-ventajas-funciones-y-beneficios\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/logity.com\/site\/wp-content\/uploads\/2025\/08\/delivery-guy-clicking-bell_23-2148593098-300x225.jpg\" class=\"attachment-medium size-medium wp-image-58687\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/logity.com\/site\/pt\/vale-la-pena-instalar-un-videoportero-inteligente-ventajas-funciones-y-beneficios\/\" >\n\t\t\t\t\u00bfVale la pena instalar un videoportero inteligente? Ventajas, funciones y beneficios\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t08\/08\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNenhum coment\u00e1rio\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>En el mundo actual, la seguridad y el control de acceso se han convertido en aspectos cruciales para cualquier propiedad. Una de las herramientas m\u00e1s<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/logity.com\/site\/pt\/vale-la-pena-instalar-un-videoportero-inteligente-ventajas-funciones-y-beneficios\/\" aria-label=\"Leia mais sobre \u00bfVale la pena instalar un videoportero inteligente? Ventajas, funciones y beneficios\" tabindex=\"-1\" >\n\t\t\tConsulte Mais informa\u00e7\u00e3o &quot;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-58677 post type-post status-publish format-standard has-post-thumbnail hentry category-sin-categoria\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/logity.com\/site\/pt\/citofono-ip-vs-citofono-analogico-ventajas-diferencias-y-cual-elegir-para-su-propiedad\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/logity.com\/site\/wp-content\/uploads\/2025\/08\/shot-pretty-young-woman-using-home-automation-system-digital-tablet-regulate-temperature_519356-1881-300x200.jpg\" class=\"attachment-medium size-medium wp-image-58680\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/logity.com\/site\/pt\/citofono-ip-vs-citofono-analogico-ventajas-diferencias-y-cual-elegir-para-su-propiedad\/\" >\n\t\t\t\tCit\u00f3fono IP vs. Cit\u00f3fono anal\u00f3gico: ventajas, diferencias y cu\u00e1l elegir para su propiedad\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t08\/08\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNenhum coment\u00e1rio\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>La seguridad y el control de acceso son aspectos fundamentales en cualquier tipo de propiedad, ya sea residencial, comercial o empresarial. Una de las herramientas<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/logity.com\/site\/pt\/citofono-ip-vs-citofono-analogico-ventajas-diferencias-y-cual-elegir-para-su-propiedad\/\" aria-label=\"Leia mais sobre Cit\u00f3fono IP vs. Cit\u00f3fono anal\u00f3gico: ventajas, diferencias y cu\u00e1l elegir para su propiedad\" tabindex=\"-1\" >\n\t\t\tConsulte Mais informa\u00e7\u00e3o &quot;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-58588 post type-post status-publish format-standard has-post-thumbnail hentry category-sin-categoria\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/logity.com\/site\/pt\/la-evolucion-del-acceso-residencial-como-el-acceso-inteligente-y-la-citofonia-inteligente-estan-transformando-los-edificios-modernos\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/logity.com\/site\/wp-content\/uploads\/2025\/07\/woman-touching-control-panel-wall-corridor_259150-60378-300x200.jpg\" class=\"attachment-medium size-medium wp-image-58591\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/logity.com\/site\/pt\/la-evolucion-del-acceso-residencial-como-el-acceso-inteligente-y-la-citofonia-inteligente-estan-transformando-los-edificios-modernos\/\" >\n\t\t\t\tLa evoluci\u00f3n del acceso residencial: c\u00f3mo el acceso inteligente y la citofon\u00eda inteligente est\u00e1n transformando los edificios modernos\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t16\/07\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNenhum coment\u00e1rio\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u00bfQu\u00e9 es el control de acceso para edificios y por qu\u00e9 es tan importante hoy? El control de acceso para edificios se refiere al conjunto<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/logity.com\/site\/pt\/la-evolucion-del-acceso-residencial-como-el-acceso-inteligente-y-la-citofonia-inteligente-estan-transformando-los-edificios-modernos\/\" aria-label=\"Leia mais sobre La evoluci\u00f3n del acceso residencial: c\u00f3mo el acceso inteligente y la citofon\u00eda inteligente est\u00e1n transformando los edificios modernos\" tabindex=\"-1\" >\n\t\t\tConsulte Mais informa\u00e7\u00e3o &quot;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>El lunes 4 de octubre la aplicaci\u00f3n gratuita de mensajer\u00eda instant\u00e1nea registr\u00f3 una ca\u00edda mundial. Una falla que nos deja una gran reflexi\u00f3n frente a evaluar si la comunicaci\u00f3n de tu gesti\u00f3n administrativa y de la comunidad residencial depende de esta aplicaci\u00f3n. La primera falla que present\u00f3 WhatsApp fue en su versi\u00f3n Web y posteriormente [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":57125,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-57124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-video-citofonia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfY si ma\u00f1ana se cae completamente WhatsApp? \u00bfQu\u00e9 suceder\u00eda con la comunicaci\u00f3n en tu comunidad? - Logity<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/logity.com\/site\/pt\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfY si ma\u00f1ana se cae completamente WhatsApp? \u00bfQu\u00e9 suceder\u00eda con la comunicaci\u00f3n en tu comunidad?\" \/>\n<meta property=\"og:description\" content=\"El lunes 4 de octubre la aplicaci\u00f3n gratuita de mensajer\u00eda instant\u00e1nea registr\u00f3 una ca\u00edda mundial. Una falla que nos deja una gran reflexi\u00f3n frente a evaluar si la comunicaci\u00f3n de tu gesti\u00f3n administrativa y de la comunidad residencial depende de esta aplicaci\u00f3n. La primera falla que present\u00f3 WhatsApp fue en su versi\u00f3n Web y posteriormente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/logity.com\/site\/pt\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Logity\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-12T14:45:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Articulos-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t<meta property=\"og:image:height\" content=\"372\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Logity\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Logity\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\\\/\"},\"author\":{\"name\":\"Logity\",\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/#\\\/schema\\\/person\\\/de3b49e6d80ca08ca6272eceeb057a4f\"},\"headline\":\"\u00bfY si ma\u00f1ana se cae completamente WhatsApp? \u00bfQu\u00e9 suceder\u00eda con la comunicaci\u00f3n en tu comunidad?\",\"datePublished\":\"2021-10-12T14:45:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\\\/\"},\"wordCount\":451,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/logity.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Articulos-2.jpg\",\"articleSection\":[\"Video citofonia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/logity.com\\\/site\\\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\\\/\",\"url\":\"https:\\\/\\\/logity.com\\\/site\\\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\\\/\",\"name\":\"\u00bfY si ma\u00f1ana se cae completamente WhatsApp? \u00bfQu\u00e9 suceder\u00eda con la comunicaci\u00f3n en tu comunidad? - Logity\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/logity.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Articulos-2.jpg\",\"datePublished\":\"2021-10-12T14:45:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/#\\\/schema\\\/person\\\/de3b49e6d80ca08ca6272eceeb057a4f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/logity.com\\\/site\\\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/logity.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Articulos-2.jpg\",\"contentUrl\":\"https:\\\/\\\/logity.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Articulos-2.jpg\",\"width\":980,\"height\":372},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/logity.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfY si ma\u00f1ana se cae completamente WhatsApp? \u00bfQu\u00e9 suceder\u00eda con la comunicaci\u00f3n en tu comunidad?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/logity.com\\\/site\\\/\",\"name\":\"Logity\",\"description\":\"Citofon\u00eda Virtual Inteligente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/logity.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/logity.com\\\/site\\\/#\\\/schema\\\/person\\\/de3b49e6d80ca08ca6272eceeb057a4f\",\"name\":\"Logity\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa9704a026975daece93256998a9d8bf460822a7b813251839bcf3edb214ca45?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa9704a026975daece93256998a9d8bf460822a7b813251839bcf3edb214ca45?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa9704a026975daece93256998a9d8bf460822a7b813251839bcf3edb214ca45?s=96&d=mm&r=g\",\"caption\":\"Logity\"},\"url\":\"https:\\\/\\\/logity.com\\\/site\\\/pt\\\/author\\\/logity\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfY si ma\u00f1ana se cae completamente WhatsApp? \u00bfQu\u00e9 suceder\u00eda con la comunicaci\u00f3n en tu comunidad? - Logity","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/logity.com\/site\/pt\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\/","og_locale":"pt_BR","og_type":"article","og_title":"\u00bfY si ma\u00f1ana se cae completamente WhatsApp? \u00bfQu\u00e9 suceder\u00eda con la comunicaci\u00f3n en tu comunidad?","og_description":"El lunes 4 de octubre la aplicaci\u00f3n gratuita de mensajer\u00eda instant\u00e1nea registr\u00f3 una ca\u00edda mundial. Una falla que nos deja una gran reflexi\u00f3n frente a evaluar si la comunicaci\u00f3n de tu gesti\u00f3n administrativa y de la comunidad residencial depende de esta aplicaci\u00f3n. La primera falla que present\u00f3 WhatsApp fue en su versi\u00f3n Web y posteriormente [&hellip;]","og_url":"https:\/\/logity.com\/site\/pt\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\/","og_site_name":"Logity","article_published_time":"2021-10-12T14:45:07+00:00","og_image":[{"width":980,"height":372,"url":"https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Articulos-2.jpg","type":"image\/jpeg"}],"author":"Logity","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Logity","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/logity.com\/site\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\/#article","isPartOf":{"@id":"https:\/\/logity.com\/site\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\/"},"author":{"name":"Logity","@id":"https:\/\/logity.com\/site\/#\/schema\/person\/de3b49e6d80ca08ca6272eceeb057a4f"},"headline":"\u00bfY si ma\u00f1ana se cae completamente WhatsApp? \u00bfQu\u00e9 suceder\u00eda con la comunicaci\u00f3n en tu comunidad?","datePublished":"2021-10-12T14:45:07+00:00","mainEntityOfPage":{"@id":"https:\/\/logity.com\/site\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\/"},"wordCount":451,"commentCount":0,"image":{"@id":"https:\/\/logity.com\/site\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\/#primaryimage"},"thumbnailUrl":"https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Articulos-2.jpg","articleSection":["Video citofonia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/logity.com\/site\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/logity.com\/site\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\/","url":"https:\/\/logity.com\/site\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\/","name":"\u00bfY si ma\u00f1ana se cae completamente WhatsApp? \u00bfQu\u00e9 suceder\u00eda con la comunicaci\u00f3n en tu comunidad? - Logity","isPartOf":{"@id":"https:\/\/logity.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/logity.com\/site\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\/#primaryimage"},"image":{"@id":"https:\/\/logity.com\/site\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\/#primaryimage"},"thumbnailUrl":"https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Articulos-2.jpg","datePublished":"2021-10-12T14:45:07+00:00","author":{"@id":"https:\/\/logity.com\/site\/#\/schema\/person\/de3b49e6d80ca08ca6272eceeb057a4f"},"breadcrumb":{"@id":"https:\/\/logity.com\/site\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/logity.com\/site\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/logity.com\/site\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\/#primaryimage","url":"https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Articulos-2.jpg","contentUrl":"https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Articulos-2.jpg","width":980,"height":372},{"@type":"BreadcrumbList","@id":"https:\/\/logity.com\/site\/y-si-manana-se-cae-completamente-whatsapp-que-sucederia-con-la-comunicacion-en-tu-comunidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/logity.com\/site\/"},{"@type":"ListItem","position":2,"name":"\u00bfY si ma\u00f1ana se cae completamente WhatsApp? \u00bfQu\u00e9 suceder\u00eda con la comunicaci\u00f3n en tu comunidad?"}]},{"@type":"WebSite","@id":"https:\/\/logity.com\/site\/#website","url":"https:\/\/logity.com\/site\/","name":"Logidade","description":"Sistema de telefone virtual inteligente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/logity.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/logity.com\/site\/#\/schema\/person\/de3b49e6d80ca08ca6272eceeb057a4f","name":"Logidade","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/fa9704a026975daece93256998a9d8bf460822a7b813251839bcf3edb214ca45?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fa9704a026975daece93256998a9d8bf460822a7b813251839bcf3edb214ca45?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa9704a026975daece93256998a9d8bf460822a7b813251839bcf3edb214ca45?s=96&d=mm&r=g","caption":"Logity"},"url":"https:\/\/logity.com\/site\/pt\/author\/logity\/"}]}},"jetpack_featured_media_url":"https:\/\/logity.com\/site\/wp-content\/uploads\/2021\/10\/Articulos-2.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/logity.com\/site\/pt\/wp-json\/wp\/v2\/posts\/57124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/logity.com\/site\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/logity.com\/site\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/logity.com\/site\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/logity.com\/site\/pt\/wp-json\/wp\/v2\/comments?post=57124"}],"version-history":[{"count":0,"href":"https:\/\/logity.com\/site\/pt\/wp-json\/wp\/v2\/posts\/57124\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/logity.com\/site\/pt\/wp-json\/wp\/v2\/media\/57125"}],"wp:attachment":[{"href":"https:\/\/logity.com\/site\/pt\/wp-json\/wp\/v2\/media?parent=57124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/logity.com\/site\/pt\/wp-json\/wp\/v2\/categories?post=57124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/logity.com\/site\/pt\/wp-json\/wp\/v2\/tags?post=57124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}